{"id":324,"date":"2015-04-29T12:15:59","date_gmt":"2015-04-29T12:15:59","guid":{"rendered":"http:\/\/www.sindilat.com.br\/site\/2015\/04\/29\/palestra-coloca-em-pauta-a-sucessao-na-propriedade-rural\/"},"modified":"2015-04-29T12:15:59","modified_gmt":"2015-04-29T12:15:59","slug":"palestra-coloca-em-pauta-a-sucessao-na-propriedade-rural","status":"publish","type":"post","link":"https:\/\/www.sindilat.com.br\/site\/2015\/04\/29\/palestra-coloca-em-pauta-a-sucessao-na-propriedade-rural\/","title":{"rendered":"Palestra coloca em pauta a sucess\u00e3o na propriedade rural"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-109\" src=\"http:\/\/www.sindilat.com.br\/site\/wp-content\/uploads\/2015\/02\/3%C2%BAano.jpg\" alt=\"3\u00baano\" style=\"float: right;\" width=\"290\" height=\"240\" \/>Com o objetivo de discutir o tema Sucess\u00e3o da Propriedade Rural, a Emater, em parceria com a Embrapa Pecu\u00e1ria Sul e a prefeitura, realizou uma palestra recente para jovens provenientes do meio rural. O evento aconteceu durante a Mostra Agropecu\u00e1ria, que comemora os 15 anos de emancipa\u00e7\u00e3o do munic\u00edpio.<\/p>\n<p style=\"text-align: justify;\">Para iniciar a atividade, o soci\u00f3logo da Embrapa Pecu\u00e1ria Sul, Jorge Sant'Anna, falou sobre os aspectos que envolvem a decis\u00e3o do jovem permanecer na atividade rural, ou ir buscar outras experi\u00eancias no meio urbano. Para Sant'Anna, muitos fatores podem contribuir para que o jovem continue no meio rural. Ele acredita que melhorar as condi\u00e7\u00f5es de renda e trabalho, atrav\u00e9s de ci\u00eancia e tecnologia, \u00e9 um ponto que deve ajudar. \"O meio rural n\u00e3o precisa ser atrasado, explorador e prec\u00e1rio\", diz. Segundo ele, outra quest\u00e3o que deve ser pensada pelo governo \u00e9 o desenvolvimento de pol\u00edticas p\u00fablicas que auxiliem na conquista de cr\u00e9dito, acesso \u00e0 comunica\u00e7\u00e3o, como internet e telefonia m\u00f3vel de qualidade. \"\u00c9 preciso haver uma mudan\u00e7a de mentalidade.<\/p>\n<p style=\"text-align: justify;\">A sucess\u00e3o rural, muitas vezes, envolve pensar na morte de um ente querido, e isso acaba sendo um tabu. Tamb\u00e9m acaba mexendo com o poder paternal, pois para ela transcorrer com naturalidade \u00e9 preciso que o chefe da fam\u00edlia perca seu poder ou pelo menos passe a dividi-lo com o mais jovem\", explica o soci\u00f3logo. De acordo com Sant'Anna, a propriedade rural precisa come\u00e7ar a ser vista como uma empresa familiar. \"Come\u00e7ar a enxergar a produ\u00e7\u00e3o rural atrav\u00e9s da perspectiva moderna da teoria da administra\u00e7\u00e3o pode fazer com que a sucess\u00e3o seja um assunto debatido com mais facilidade\", conclui ele.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a palestra do soci\u00f3logo, o p\u00fablico foi divido em dois grupos para realizar uma t\u00e9cnica de representa\u00e7\u00e3o teatral. Um deles desenvolveu uma situa\u00e7\u00e3o em que um dos filhos da fam\u00edlia deveria ter o desejo de permanecer na propriedade. No outro, os jovens possu\u00edam o desejo de partir para o meio urbano. Nas duas situa\u00e7\u00f5es os participantes apresentaram os motivos para cada uma daquelas escolhas serem feitas, atrav\u00e9s de di\u00e1logos teatrais. Atividade terminou com uma mesa redonda sobre o tema, onde o p\u00fablico presente exp\u00f4s suas hist\u00f3rias e discutiu sobre os fatores expostos.<\/p>\n<p style=\"text-align: justify;\">Para a extensionista de bem-estar social da Emater, Luana Alves, a discuss\u00e3o do tema \u00e9 importante. De acordo com ela a constante evas\u00e3o rural desperta a preocupa\u00e7\u00e3o com o futuro da produ\u00e7\u00e3o de alimentos. (Jornal do Com\u00e9rcio)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de discutir o tema Sucess\u00e3o da Propriedade Rural, a Emater, em parceria com a Embrapa Pecu\u00e1ria Sul e a prefeitura, realizou uma palestra recente para jovens provenientes do meio rural. O evento aconteceu durante a Mostra Agropecu\u00e1ria, que comemora os 15 anos de emancipa\u00e7\u00e3o do munic\u00edpio. Para iniciar a atividade, o soci\u00f3logo <a href=\"https:\/\/www.sindilat.com.br\/site\/2015\/04\/29\/palestra-coloca-em-pauta-a-sucessao-na-propriedade-rural\/\" class=\"more-link\">...continuar lendo<span class=\"screen-reader-text\"> \"Palestra coloca em pauta a sucess\u00e3o na propriedade rural\"<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":{"0":"post-324","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"h-entry","9":"hentry","10":"h-as-article"},"_links":{"self":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/comments?post=324"}],"version-history":[{"count":0,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media\/109"}],"wp:attachment":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media?parent=324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/categories?post=324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/tags?post=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}