{"id":320,"date":"2015-04-27T17:13:30","date_gmt":"2015-04-27T17:13:30","guid":{"rendered":"http:\/\/www.sindilat.com.br\/site\/2015\/04\/27\/evento-sobre-diagnostico-de-brucelose-animal-e-promovido-pela-ufsm-e-secretaria-da-agricultura-e-pecuaria\/"},"modified":"2015-04-27T17:13:30","modified_gmt":"2015-04-27T17:13:30","slug":"evento-sobre-diagnostico-de-brucelose-animal-e-promovido-pela-ufsm-e-secretaria-da-agricultura-e-pecuaria","status":"publish","type":"post","link":"https:\/\/www.sindilat.com.br\/site\/2015\/04\/27\/evento-sobre-diagnostico-de-brucelose-animal-e-promovido-pela-ufsm-e-secretaria-da-agricultura-e-pecuaria\/","title":{"rendered":"Evento sobre diagn\u00f3stico de brucelose animal \u00e9 promovido pela UFSM e Secretaria da Agricultura e Pecu\u00e1ria"},"content":{"rendered":"<p style=\"text-align: justify;\">27\/04\/2015<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-317\" src=\"http:\/\/www.sindilat.com.br\/site\/wp-content\/uploads\/2015\/04\/68.png\" alt=\"68\" style=\"float: right;\" width=\"430\" height=\"312\" \/>Discutir o diagn\u00f3stico de brucelose animal e conhecer as pol\u00edticas atuais sobre a doen\u00e7a s\u00e3o os objetivos do encontro sobre brucelose animal programado para o pr\u00f3ximo dia 30 de abril. O evento \u00e9 uma promo\u00e7\u00e3o do Departamento de Microbiologia e Parasitologia da Universidade Federal de Santa Maria (UFSM), com apoio da Supervis\u00e3o Regional de Santa Maria do Departamento de Defesa Agropecu\u00e1ria (DDA) da Secretaria da Agricultura e Pecu\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">A programa\u00e7\u00e3o inicia \u00e0s 8h da manh\u00e3 da pr\u00f3xima quinta-feira e prossegue durante todo o dia, no audit\u00f3rio Audimax, na UFSM. O professor da UFSM, Geder Paulo Herrmann, abre as palestras apresentando O Projeto de Diagn\u00f3stico de Brucelose Animal. A palestra sobre desempenho de teste de brucelose ser\u00e1 apresentada pela m\u00e9dica veterin\u00e1ria Alessandra Lopes Goelzer, e o representante da Associa\u00e7\u00e3o Brasileira de Criadores de Ovinos (ARCO), Edemundo Gressler, ir\u00e1 encerrar as atividades da manh\u00e3 falando sobre a percep\u00e7\u00e3o do Programa Estadual de Sanidade Ovina (PROESO) pelos criadores.<\/p>\n<p style=\"text-align: justify;\">Pela parte da tarde, os fiscais agropecu\u00e1rios da SAP, Ivo Kohek J\u00fanior e Gisane Lanes de Almeida, ir\u00e3o falar sobre epididimite ovina, PROESO e sobre a\u00e7\u00f5es de controle da tuberculose e brucelose no Estado. O m\u00e9dico veterin\u00e1rio Rafael Martins, representante do Minist\u00e9rio da Agricultura, ir\u00e1 encerrar os debates com uma palestra sobre a situa\u00e7\u00e3o do Programa Nacional de Controle e Erradica\u00e7\u00e3o da Brucelose e Tuberculose (PNCEBT) e sobre brucelose ovina.<\/p>\n<p style=\"text-align: justify;\">O p\u00fablico alvo do evento, que ter\u00e1 uma carga hor\u00e1ria de oito horas, s\u00e3o m\u00e9dicos veterin\u00e1rios, secret\u00e1rios de agricultura dos munic\u00edpios do Corede Central e alunos do curso de medicina veterin\u00e1ria. (Assessoria de imprensa da Secretaria da Agricultura e Pecu\u00e1ria\/ DDA \/ Regi\u00e3o Central)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>27\/04\/2015 Discutir o diagn\u00f3stico de brucelose animal e conhecer as pol\u00edticas atuais sobre a doen\u00e7a s\u00e3o os objetivos do encontro sobre brucelose animal programado para o pr\u00f3ximo dia 30 de abril. O evento \u00e9 uma promo\u00e7\u00e3o do Departamento de Microbiologia e Parasitologia da Universidade Federal de Santa Maria (UFSM), com apoio da Supervis\u00e3o Regional de <a href=\"https:\/\/www.sindilat.com.br\/site\/2015\/04\/27\/evento-sobre-diagnostico-de-brucelose-animal-e-promovido-pela-ufsm-e-secretaria-da-agricultura-e-pecuaria\/\" class=\"more-link\">...continuar lendo<span class=\"screen-reader-text\"> \"Evento sobre diagn\u00f3stico de brucelose animal \u00e9 promovido pela UFSM e Secretaria da Agricultura e Pecu\u00e1ria\"<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":{"0":"post-320","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"h-entry","9":"hentry","10":"h-as-article"},"_links":{"self":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":0,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media\/317"}],"wp:attachment":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media?parent=320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/categories?post=320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/tags?post=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}