{"id":15905,"date":"2024-12-12T18:54:28","date_gmt":"2024-12-12T18:54:28","guid":{"rendered":"https:\/\/www.sindilat.com.br\/site\/?p=15905"},"modified":"2024-12-12T18:54:28","modified_gmt":"2024-12-12T18:54:28","slug":"sindilat-apoia-investigacao-de-dumping-no-leite","status":"publish","type":"post","link":"https:\/\/www.sindilat.com.br\/site\/2024\/12\/12\/sindilat-apoia-investigacao-de-dumping-no-leite\/","title":{"rendered":"Sindilat apoia investiga\u00e7\u00e3o de dumping no leite"},"content":{"rendered":"<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15129\" src=\"https:\/\/www.sindilat.com.br\/site\/wp-content\/uploads\/2024\/08\/Logo-Sindilat-300x258.png\" alt=\"\" width=\"300\" height=\"258\" srcset=\"https:\/\/www.sindilat.com.br\/site\/wp-content\/uploads\/2024\/08\/Logo-Sindilat-300x258.png 300w, https:\/\/www.sindilat.com.br\/site\/wp-content\/uploads\/2024\/08\/Logo-Sindilat.png 383w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">O Sindicato da Ind\u00fastria de Latic\u00ednios do RS (Sindilat\/RS) v\u00ea como positiva a decis\u00e3o do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) de abrir investiga\u00e7\u00e3o da pr\u00e1tica de dumping na compra de leite em p\u00f3 importado. A medida deve contribuir para o equil\u00edbrio do mercado nacional de leite, que vem sofrendo com a compra de produtos importados de pa\u00edses do Prata, muitas vezes por empresas do varejo e atravessadores no atacado. A decis\u00e3o atende \u00e0 solicita\u00e7\u00e3o feita em agosto deste ano pela Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA) e publicada na quarta-feira (11\/12), na Circular n\u00ba 72\/2024 do MDIC no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p>O Sindilat acompanha de perto o fluxo de importa\u00e7\u00f5es de leite e queijos pelo Brasil e avalia os danos desse processo \u00e0 ind\u00fastria nacional. O que acontece, explica o secret\u00e1rio executivo, Darlan Palharini, \u00e9 que o custo dos derivados importados que entram no Brasil est\u00e3o abaixo do valor praticado no mercado nacional. \u201cNos falta competitividade, mas \u00e9 preciso estar sempre atento ao cumprimento dos tratados internacionais e das boas pr\u00e1ticas comerciais\u201d, disse. A cria\u00e7\u00e3o de novos agentes importadores no segmento produtivo tamb\u00e9m preocupa. Palharini explica que com as restri\u00e7\u00f5es delineadas \u00e0 importa\u00e7\u00e3o pelos latic\u00ednios surgiram empresas especializadas em comprar produtos l\u00e1cteos e entregar direto ao varejo, sem uma correla\u00e7\u00e3o vantajosa ao Brasil quanto ao n\u00famero de empregos, renda e riquezas geradas.<\/p>\n<p>Conforme levantamento divulgado pela CNA, em 2022, o Brasil importou 942 milh\u00f5es de litros de leite em p\u00f3. J\u00e1 em 2023, esse valor chegou a 1,7 bilh\u00e3o de litros. At\u00e9 novembro deste ano, j\u00e1 foram importados o equivalente a 1,4 bilh\u00e3o de litros, vindos, principalmente, de pa\u00edses do Mercosul. Desse total, 760 milh\u00f5es de litros s\u00e3o da Argentina, 566 milh\u00f5es do Uruguai e 97 milh\u00f5es do Paraguai.<\/p>\n<p>Em quatro n\u00edveis de a\u00e7\u00f5es para o mercado nacional, o Sindilat pleiteia mudan\u00e7a na incid\u00eancia de PIS\/COFINS com aumento do cr\u00e9dito presumido para 100% na compra de insumos, a venda internacional da produ\u00e7\u00e3o com a ado\u00e7\u00e3o de um Pr\u00eamio para Escoamento do Produto (PEP), a oferta de linhas de cr\u00e9dito pela Uni\u00e3o para produtores e ind\u00fastrias de latic\u00ednios e o estabelecimento do Fundo Nacional de Sanidade do Leite (FNSL).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sindicato da Ind\u00fastria de Latic\u00ednios do RS (Sindilat\/RS) v\u00ea como positiva a decis\u00e3o do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) de abrir investiga\u00e7\u00e3o da pr\u00e1tica de dumping na compra de leite em p\u00f3 importado. A medida deve contribuir para o equil\u00edbrio do mercado nacional de leite, que vem sofrendo com a compra <a href=\"https:\/\/www.sindilat.com.br\/site\/2024\/12\/12\/sindilat-apoia-investigacao-de-dumping-no-leite\/\" class=\"more-link\">...continuar lendo<span class=\"screen-reader-text\"> \"Sindilat apoia investiga\u00e7\u00e3o de dumping no leite\"<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":15129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18,31],"tags":[],"class_list":{"0":"post-15905","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-noticias-sindilat-tv","9":"h-entry","10":"hentry","11":"h-as-article"},"_links":{"self":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/15905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/comments?post=15905"}],"version-history":[{"count":1,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/15905\/revisions"}],"predecessor-version":[{"id":15906,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/15905\/revisions\/15906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media\/15129"}],"wp:attachment":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media?parent=15905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/categories?post=15905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/tags?post=15905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}