{"id":14409,"date":"2024-04-09T19:29:50","date_gmt":"2024-04-09T19:29:50","guid":{"rendered":"https:\/\/www.sindilat.com.br\/site\/?p=14409"},"modified":"2024-04-09T19:32:23","modified_gmt":"2024-04-09T19:32:23","slug":"09-04-2024","status":"publish","type":"post","link":"https:\/\/www.sindilat.com.br\/site\/2024\/04\/09\/09-04-2024\/","title":{"rendered":"09\/04\/2024"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" style=\"text-align: justify; font-size: 1rem;\" src=\"https:\/\/dl.dnzdns.com\/v\/uuURf8ABF0257\" alt=\"Newsletter Sindilat_RS\" width=\"1159\" height=\"207\"><\/p>\n<div id=\"icpbravoaccess_loaded\">\n<div id=\"icpbravoaccess_loaded\">\n<div id=\"icpbravoaccess_loaded\">\n<p style=\"text-align: justify;\">Porto Alegre, 09 de abril de 2024&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ano 18 - N\u00b0 4.122<\/p>\n<\/div>\n<\/div>\n<\/div>\n<hr>\n<div>\n<p style=\"text-align: justify;\"><b>Leite v\u00ea chance de desfecho da pauta tribut\u00e1ria nos pr\u00f3ximos dias<br \/>\n<\/b><br \/>\nPr\u00f3ximo a liderar uma viagem para It\u00e1lia e Alemanha em busca de novos neg\u00f3cios e estreitar la\u00e7os com esses dois pa\u00edses, o governador Eduardo Leite tem esperan\u00e7a que, antes do embarque para Europa marcado para a pr\u00f3xima sexta-feira (12), possa haver uma defini\u00e7\u00e3o sobre a mudan\u00e7a tribut\u00e1ria que est\u00e1 sendo discutida no Rio Grande do Sul. \u201cEstamos fazendo conversas, com bancadas (de deputados), com setores produtivos e h\u00e1 uma possibilidade de a gente ter uma defini\u00e7\u00e3o ainda nessa semana, antes da viagem\u201d, afirma o governador.<\/p>\n<p style=\"text-align: justify;\">Em princ\u00edpio, a inten\u00e7\u00e3o do governo ga\u00facho \u00e9 confirmar uma eleva\u00e7\u00e3o de al\u00edquota do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Presta\u00e7\u00e3o de Servi\u00e7os (ICMS) de 17% para 19%. Leite comentou rapidamente sobre a quest\u00e3o tribut\u00e1ria ao final da instala\u00e7\u00e3o da Frente Parlamentar Brasil\/It\u00e1lia, ocorrida nesta segunda-feira (8), no Teatro Dante Barone, na Assembleia Legislativa, em Porto Alegre.<\/p>\n<p style=\"text-align: justify;\">Na ocasi\u00e3o, o governador tamb\u00e9m mencionou a miss\u00e3o do governo ga\u00facho \u00e0 Europa e enfatizou que, entre outros pontos, a iniciativa tem como meta valorizar os 150 anos de imigra\u00e7\u00e3o italiana no Rio Grande do Sul, a serem completados em 2025. Outro foco da viagem ser\u00e1 expor os vinhos ga\u00fachos. \u201cO Estado est\u00e1 patrocinando um estande na Vinitaly (em Verona), evento dedicado a abrir mercado consumidor para a nossa produ\u00e7\u00e3o vitivin\u00edcola\u201d, ressalta Leite.<\/p>\n<p style=\"text-align: justify;\">Posteriormente, na passagem por Roma, ser\u00e3o realizados encontros com empresas da \u00e1rea de infraestrutura e o foco ser\u00e1 convencer esses grupos a investirem em novas oportunidades de concess\u00e3o rodovi\u00e1rias e em outras frentes no Rio Grande do Sul. Tamb\u00e9m ser\u00e1 feito o convite ao Papa Francisco, que \u00e9 jesu\u00edta, para visitar o Rio Grande do Sul em 2026, quando haver\u00e1 a comemora\u00e7\u00e3o dos 400 anos das Miss\u00f5es jesu\u00edticas no Estado.<\/p>\n<p style=\"text-align: justify;\">Na parte da viagem que abrange a Alemanha, al\u00e9m do t\u00f3pico das comemora\u00e7\u00f5es dos 200 anos da imigra\u00e7\u00e3o germ\u00e2nica, que acontecer\u00e3o neste ano, ser\u00e3o prospectados novos neg\u00f3cios e haver\u00e1 a participa\u00e7\u00e3o na Feira Industrial de Hannover. O embaixador da It\u00e1lia no Brasil, Alessandro Cortese, considera importante a viagem da comitiva ga\u00facha \u00e0 Europa, pois Leite ir\u00e1 apresentar os vinhos do Estado em uma das maiores feiras desse setor naquele continente. \u201cE o vinho do Rio Grande do Sul \u00e9 uma heran\u00e7a dos italianos que chegaram h\u00e1 150 anos e ensinaram a cultivar a uva e fazer a bebida\u201d, frisa Cortese.<\/p>\n<p style=\"text-align: justify;\">Ele acrescenta que o vinho ga\u00facho \u00e9 de boa qualidade, especialmente, os espumantes. O embaixador ressalta ainda que, politicamente, \u00e9 muito importante a presen\u00e7a do governador do Rio Grande do Sul na It\u00e1lia para fortalecer os la\u00e7os entre as duas regi\u00f5es. No evento desta segunda-feira, Leite assinou decreto criando o comit\u00ea de organiza\u00e7\u00e3o dos festejos de 150 anos da imigra\u00e7\u00e3o italiana no Estado.<\/p>\n<p style=\"text-align: justify;\">\u201cA partir de agora, de forma oficial, institui\u00e7\u00f5es do poder Executivo, do Legislativo e da sociedade civil se reunir\u00e3o para desenharem todo o calend\u00e1rio de organiza\u00e7\u00f5es\u201d, comenta o deputado estadual Guilherme Pasin (PP), presidente da Frente Parlamentar Brasil\/It\u00e1lia. O deputado acrescenta que ser\u00e1 definido, por exemplo, se ser\u00e1 feito um \u00fanico evento ou se ser\u00e1 levada para cada regi\u00e3o de imigra\u00e7\u00e3o italiana no Estado alguma a\u00e7\u00e3o e descentralizar os atos da celebra\u00e7\u00e3o. Ainda no encontro dessa segunda-feira, foi feita a entrega da Medalha da 56\u00aa Legislatura ao c\u00f4nsul-geral da It\u00e1lia em Porto Alegre, Valerio Caruso. (Jornal do Com\u00e9rcio)<\/p>\n<hr>\n<p style=\"text-align: justify;\"><b><\/b><b>Argentina: exporta\u00e7\u00f5es de leite decolaram, mas ainda h\u00e1 medo<br \/>\n<\/b><br \/>\nEmbora em divisas em d\u00f3lares tenha significado apenas um aumento de 1%, nos dois primeiros meses do ano as exporta\u00e7\u00f5es em toneladas e litros de leite da Argentina aumentaram 11% e 17%, respectivamente. Em detalhes, nos meses de janeiro e fevereiro de 2024, houve exporta\u00e7\u00f5es de 70.036 toneladas e 492,6 milh\u00f5es de litros de leite equivalente.<\/p>\n<p style=\"text-align: justify;\">O n\u00famero vem de um relat\u00f3rio preparado pelo Minist\u00e9rio da Agricultura, que tamb\u00e9m destacou que a contribui\u00e7\u00e3o do setor foi de US$ 251 milh\u00f5es. Vale lembrar que, por outro lado, houve uma queda acentuada na produ\u00e7\u00e3o nas fazendas leiteiras de mais de 15% no mesmo per\u00edodo e, em particular, em fevereiro em rela\u00e7\u00e3o ao mesmo m\u00eas em 2023, foi 17,8% menor. O decl\u00ednio pode ser maior no m\u00eas atual.<\/p>\n<p style=\"text-align: justify;\">O Diretor Nacional de L\u00e1cteos, Sebasti\u00e1n Alconada, elogiou a pol\u00edtica do atual governo de manter o imposto de 0% da administra\u00e7\u00e3o anterior - a validade da medida \u00e9 at\u00e9 30 de junho - que somada \u00e0 mudan\u00e7a na taxa de c\u00e2mbio permitiu que as exporta\u00e7\u00f5es come\u00e7assem a \"ser neg\u00f3cios\".<\/p>\n<p style=\"text-align: justify;\">\"A exporta\u00e7\u00e3o n\u00e3o foi maior devido a uma quest\u00e3o sazonal em que h\u00e1 menos oferta, o que atrapalhou um pouco\", disse ele.<\/p>\n<p style=\"text-align: justify;\">O consultor do setor de l\u00e1cteos, Jos\u00e9 Quintana, lembrou que, apesar de \"uma queda fenomenal na produ\u00e7\u00e3o em fevereiro passado, as exporta\u00e7\u00f5es cresceram muito em litros equivalentes\". \"Estamos exportando 30% do leite produzido e isso \u00e9 muito bom. Isso foi poss\u00edvel, primeiramente, por causa da elimina\u00e7\u00e3o dos impostos retidos na fonte e depois da desvaloriza\u00e7\u00e3o, o valor do d\u00f3lar oficial agora \u00e9 completamente diferente. E isso \u00e9 \u00fatil e tamb\u00e9m ajuda a atividade, porque o mercado dom\u00e9stico \u00e9 muito recessivo. Com todos os problemas na economia, com uma queda fenomenal na demanda, se a oferta n\u00e3o ca\u00edsse, os pre\u00e7os do mercado interno despencariam\", disse ele.<\/p>\n<p style=\"text-align: justify;\">Nesse contexto, ele ressaltou que, gra\u00e7as ao crescimento das exporta\u00e7\u00f5es, os pre\u00e7os internos podem ser sustentados. \"Se n\u00e3o estiv\u00e9ssemos exportando tudo o que estamos exportando, os pre\u00e7os internos provavelmente n\u00e3o conseguiriam acompanhar o que est\u00e1 acontecendo e n\u00e3o conseguir\u00edamos ajustar o pre\u00e7o do leite e a queda na produ\u00e7\u00e3o seria ainda pior. Por isso, eu sa\u00fado o fato de podermos exportar tudo o que \u00e9 exportado\", acrescentou.<\/p>\n<p style=\"text-align: justify;\">Cautelosamente, o presidente da Associa\u00e7\u00e3o de Pequenas e M\u00e9dias Empresas de Latic\u00ednios (Apymel), Pablo Villano, em termos de produ\u00e7\u00e3o, foi positivo e disse que a atual escassez de leite ter\u00e1 sua recupera\u00e7\u00e3o a partir de maio, quando entrarem os pastos, as reservas e os silos, mas observou que, em um mercado interno com pouco poder de compra, muito pouco \u00e9 vendido e \"est\u00e1 entrando mercadoria de fora\".<\/p>\n<p style=\"text-align: justify;\">\"Hoje os produtos importados est\u00e3o com um pre\u00e7o semelhante ou um pouco mais caro. Mas, devido \u00e0 infla\u00e7\u00e3o e aos nossos custos, \u00e9 muito prov\u00e1vel que, em um prazo n\u00e3o muito curto, ultrapassemos os pre\u00e7os estrangeiros e isso ser\u00e1 um problema\", observou.<\/p>\n<p style=\"text-align: justify;\">Ele disse que no mercado internacional os pre\u00e7os de exporta\u00e7\u00e3o est\u00e3o caindo, onde a cooperativa de latic\u00ednios Fonterra, uma das maiores do mundo, fez duas cota\u00e7\u00f5es com valores em queda.<\/p>\n<p style=\"text-align: justify;\">Nesse cen\u00e1rio, ele explicou que, sem conseguir resolver a quest\u00e3o dos custos internos, os exportadores j\u00e1 est\u00e3o pedindo uma melhora na taxa de c\u00e2mbio que agora permanece est\u00e1vel, ou seja, elev\u00e1-la para ser mais competitiva no exterior.<\/p>\n<p style=\"text-align: justify;\">\"Por enquanto as coisas est\u00e3o indo bem, voc\u00ea tem que ser competitivo para se adaptar ao pre\u00e7o internacional, o pre\u00e7o internacional n\u00e3o se adapta a voc\u00ea. Agora temos o grande dilema de como repassar os aumentos de custo para os produtos finais, incluindo o leite, que tem aumentado constantemente, e os sal\u00e1rios. Com esses pre\u00e7os do leite, as exporta\u00e7\u00f5es e o mercado interno est\u00e3o inst\u00e1veis\", disse ele.<\/p>\n<p style=\"text-align: justify;\">Nesse contexto, o presidente do Centro da Ind\u00fastria de Latic\u00ednios (CIL), Ercole Felippa, disse que em 2024 \"haver\u00e1 menos exporta\u00e7\u00f5es do que no ano passado, porque h\u00e1 uma queda significativa na produ\u00e7\u00e3o que, embora a partir do segundo semestre mude a tend\u00eancia, n\u00e3o ser\u00e1 suficiente para recuperar de alguma forma o decl\u00ednio\".<\/p>\n<p style=\"text-align: justify;\">\"Essa queda na produ\u00e7\u00e3o se refletir\u00e1 em menores volumes de exporta\u00e7\u00e3o. Hoje aquela vantagem inicial dada pela taxa de c\u00e2mbio n\u00e3o existe mais, porque o aumento de custos que ocorreu engoliu aquela vantagem que lhe deu oportunamente, e se eles voltassem a implementar as taxas de exporta\u00e7\u00e3o (DEX), claramente pelo menos no leite em p\u00f3, que \u00e9 aproximadamente 50% do que a Argentina exporta, estaria fora da competi\u00e7\u00e3o\", alertou.<\/p>\n<p style=\"text-align: justify;\">\"O que aconteceu nos dois primeiros meses do ano foi uma situa\u00e7\u00e3o pontual, que provavelmente n\u00e3o se refletir\u00e1 ao longo do ano. Isso tamb\u00e9m depender\u00e1 muito do que for adotado em termos de DEX. Vale lembrar que foram eliminadas as restitui\u00e7\u00f5es, que \u00e9 o componente tribut\u00e1rio da mercadoria a ser exportada. Foi justamente o setor de latic\u00ednios o \u00fanico para o qual as restitui\u00e7\u00f5es foram eliminadas, o que significa que esse esquema deve ser revisto, para que seja um sistema equitativo de restitui\u00e7\u00f5es, para que n\u00e3o acabemos nos tornando exportadores de impostos\", acrescentou.<\/p>\n<p style=\"text-align: justify;\">Como ele explicou, \"a quest\u00e3o das restitui\u00e7\u00f5es \u00e9 uma pol\u00edtica, inclusive prevista pela Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio, de que um governo pode devolver a seus exportadores o componente tribut\u00e1rio do bem a ser exportado, onde os produtos l\u00e1cteos tinham isso, e quando o imposto de exporta\u00e7\u00e3o de 0% foi estendido por seis meses, as restitui\u00e7\u00f5es tamb\u00e9m foram eliminadas\".<\/p>\n<p style=\"text-align: justify;\">Este ver\u00e3o de exporta\u00e7\u00f5es tem um \"fantasma\", que \u00e9 o fato de que, no final de junho, a suspens\u00e3o das reten\u00e7\u00f5es chegar\u00e1 ao fim. \"Esperamos que ningu\u00e9m pense em voltar a aplic\u00e1-las, porque isso seria terr\u00edvel para o setor. Porque os impostos retidos na fonte, especialmente nos n\u00edveis de que eles [o governo] estavam falando, custam cerca de seis centavos de d\u00f3lar por litro e algo assim, que \u00e9 uma quantia enorme de dinheiro, nos colocaria de volta em uma crise da qual finalmente parecemos estar saindo. Esperemos que isso n\u00e3o aconte\u00e7a novamente\", enfatizou Quintana. Vale lembrar que o leite em p\u00f3 pagava 9% de taxas de exporta\u00e7\u00e3o e o queijo 4,5%.<\/p>\n<p style=\"text-align: justify;\">Nessa linha, o executivo da Apymel destacou a import\u00e2ncia do fato de n\u00e3o haver tarifas de exporta\u00e7\u00e3o, embora tenha enfatizado que essa pausa de seis meses deixa muita incerteza de que \"a qualquer momento elas voltar\u00e3o\". Ele disse: \"Enfatizamos a import\u00e2ncia de n\u00e3o haver reten\u00e7\u00e3o de impostos no setor\".<\/p>\n<p style=\"text-align: justify;\">Para tranquilizar o p\u00fablico, Alconada garantiu que \"n\u00e3o est\u00e1 na agenda\" o retorno dos impostos. \"A lei omnibus contemplou a elimina\u00e7\u00e3o definitiva dos impostos retidos na fonte sobre o setor. Portanto, isso n\u00e3o est\u00e1 em nosso cen\u00e1rio. A ideia \u00e9 que tudo continue como est\u00e1 e que tentemos exportar o m\u00e1ximo que pudermos. E focar em como vamos produzir mais\", encerrou.<\/p>\n<p style=\"text-align: justify;\">As informa\u00e7\u00f5es s\u00e3o do La Naci\u00f3n, traduzidas e adaptadas pela equipe MilkPoint.<\/p>\n<p style=\"text-align: justify;\"><b>Brasileiro quer comprar produtos sustent\u00e1veis, mas n\u00e3o entende r\u00f3tulos, revela estudo<br \/>\n<\/b><br \/>\nUm estudo global da consultoria Bain &amp; Company divulgado recentemente aponta que cerca de 80% dos brasileiros s\u00e3o seriamente preocupados com quest\u00f5es envolvendo sustentabilidade e mudan\u00e7as clim\u00e1ticas. Um n\u00edvel de preocupa\u00e7\u00e3o acima da m\u00e9dia mundial levantada pelo estudo, que ficou em 65%.<\/p>\n<p style=\"text-align: justify;\">Mas ser\u00e1 que esse engajamento \u00e9 colocado em pr\u00e1tica nas compras dos brasileiros? Segundo Daniela Carbinato, que liderou o estudo, ainda existem desafios a serem vencidas nesse sentido.<\/p>\n<p style=\"text-align: justify;\">Segundo a pesquisa, 27% dos consumidores ouvidos apontam como barreira para a compra a falta de informa\u00e7\u00e3o e transpar\u00eancia sobre a sustentabilidade praticada pelas empresas respons\u00e1veis pelos produtos.<\/p>\n<p style=\"text-align: justify;\">\u201cA pergunta que esse consumidor se faz \u00e9: \u2018esse produto \u00e9 realmente sustent\u00e1vel, org\u00e2nico, vegano ou n\u00e3o?\u2019\u201d, relata Daniela.<\/p>\n<p style=\"text-align: justify;\">Ao mesmo tempo, 19% mencionaram que os r\u00f3tulos e certifica\u00e7\u00f5es s\u00e3o confusos. Por fim, 21% indicam que comprariam mais se as empresas fossem mais transparentes sobre seus produtos.<\/p>\n<p style=\"text-align: justify;\">\u201cH\u00e1 uma preocupa\u00e7\u00e3o do consumidor de acreditar que faz escolhas saud\u00e1veis e sustent\u00e1veis, mas que, na verdade, n\u00e3o s\u00e3o\u201d, destaca Daniela.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, a pesquisa mostra que, no Brasil, quase 60% dos consumidores utilizam as embalagens como principal fonte de informa\u00e7\u00e3o sobre os produtos, seguido de descri\u00e7\u00f5es online, recomenda\u00e7\u00f5es e an\u00fancios.<\/p>\n<p style=\"text-align: justify;\">\u201cEsses \u00faltimos s\u00e3o fundamentais, j\u00e1 que os consumidores pouco entendem o que os selos de certifica\u00e7\u00f5es realmente significam. \u00c9 o caso de produtos org\u00e2nicos, veganos, rastre\u00e1veis, naturais, integrais, entre outros\u201d, defende a executiva.<\/p>\n<p style=\"text-align: justify;\">Sinaliza\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify;\">Os dados sobre necessidade de sinaliza\u00e7\u00e3o em loja tamb\u00e9m chamam a aten\u00e7\u00e3o: 20% dos consumidores brasileiros a classificam como importante fonte de informa\u00e7\u00e3o, quase 1,5 vez mais do que a m\u00e9dia global considerou. \u201cIsso coloca a jornada de compra na loja como importante fator de compra na decis\u00e3o\u201d, comenta Daniela.<\/p>\n<p style=\"text-align: justify;\">Para ela, a sustentabilidade e a preocupa\u00e7\u00e3o com a sa\u00fade n\u00e3o s\u00e3o mais quest\u00f5es nichadas, abrindo um leque de oportunidades para as empresas. Mas ressalta: facilitar a comunica\u00e7\u00e3o \u00e9 fundamental.<\/p>\n<p style=\"text-align: justify;\">\"A informa\u00e7\u00e3o precisa ser direta e s\u00edmbolos n\u00e3o resolvem o problema. Os r\u00f3tulos devem ser explicativos, com comunica\u00e7\u00e3o simples, QR Codes devem ser funcionais e pr\u00e1ticos, trazendo a informa\u00e7\u00e3o sobre aquele sele da certifica\u00e7\u00e3o que aparece na embalagem. Isso \u00e9 ajudar da educa\u00e7\u00e3o do consumidor\u201d, avalia.<\/p>\n<p style=\"text-align: justify;\">As informa\u00e7\u00f5es s\u00e3o do Globo Rural, adaptadas pela equipe MilkPoint.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<hr>\n<p style=\"text-align: center;\"><strong><em>Jogo R\u00e1pido<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><i><b>Ascens\u00e3o do setor de l\u00e1cteos na China gera preocupa\u00e7\u00f5es entre os exportadores<br \/>\n<\/b>A r\u00e1pida ascens\u00e3o da China no setor de l\u00e1cteos, pronta para reivindicar o t\u00edtulo de terceiro maior produtor de leite do mundo, est\u00e1 causando inquieta\u00e7\u00e3o entre os exportadores globais. De acordo com Keith Woodford, Professor Honor\u00e1rio de Sistemas Agroalimentares da Universidade de Lincoln, o crescente setor de l\u00e1cteos na China atraiu a aten\u00e7\u00e3o dos participantes do setor em todo o mundo. Woodford enfatiza que os principais participantes, como a Fonterra e outras empresas, est\u00e3o monitorando de perto a situa\u00e7\u00e3o, reconhecendo as implica\u00e7\u00f5es significativas da evolu\u00e7\u00e3o do cen\u00e1rio de latic\u00ednios na China. Com o papel fundamental da China no mercado global de l\u00e1cteos, os exportadores permanecem vigilantes, atentos aos poss\u00edveis riscos associados \u00e0 depend\u00eancia excessiva de um \u00fanico mercado. Qualquer interrup\u00e7\u00e3o ou queda na China pode ter consequ\u00eancias catastr\u00f3ficas para os exportadores. No entanto, Woodford observa que a China est\u00e1 diversificando ativamente suas importa\u00e7\u00f5es de latic\u00ednios, mitigando algumas das preocupa\u00e7\u00f5es relacionadas \u00e0 depend\u00eancia de um \u00fanico mercado. As proje\u00e7\u00f5es indicam um aumento substancial de 25% nas importa\u00e7\u00f5es de l\u00e1cteos pela China na pr\u00f3xima d\u00e9cada, sinalizando oportunidades para os exportadores capitalizarem no mercado em expans\u00e3o. \u00c0 medida que a China continua solidificando sua posi\u00e7\u00e3o como um importante participante do setor de latic\u00ednios, os exportadores devem navegar pela din\u00e2mica em evolu\u00e7\u00e3o desse mercado crucial e, ao mesmo tempo, permanecer atentos aos poss\u00edveis riscos e oportunidades no horizonte. (As informa\u00e7\u00f5es s\u00e3o do The Dairy News, traduzidas e adaptadas pela equipe MilkPoint)<\/i><\/p>\n<hr>\n<\/div>\n<div id=\"icpbravoaccess_loaded\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Porto Alegre, 09 de abril de 2024&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ano 18 - N\u00b0 4.122 Leite v\u00ea chance de desfecho da pauta tribut\u00e1ria nos pr\u00f3ximos dias Pr\u00f3ximo a liderar uma viagem <a href=\"https:\/\/www.sindilat.com.br\/site\/2024\/04\/09\/09-04-2024\/\" class=\"more-link\">...continuar lendo<span class=\"screen-reader-text\"> \"09\/04\/2024\"<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[28],"tags":[],"class_list":{"0":"post-14409","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-newsletter","7":"h-entry","8":"hentry","9":"h-as-article"},"_links":{"self":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/14409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/comments?post=14409"}],"version-history":[{"count":5,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/14409\/revisions"}],"predecessor-version":[{"id":14414,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/posts\/14409\/revisions\/14414"}],"wp:attachment":[{"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/media?parent=14409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/categories?post=14409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindilat.com.br\/site\/wp-json\/wp\/v2\/tags?post=14409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}